{"id":390868,"date":"2026-01-30T10:14:45","date_gmt":"2026-01-30T10:14:45","guid":{"rendered":"https:\/\/glotomania.com\/p\/manteca-de-cacao-desodorizada-en-polvo-mycryo-cacao-barry-550-g-2\/"},"modified":"2026-03-24T06:52:15","modified_gmt":"2026-03-24T06:52:15","slug":"manteca-de-cacao-desodorizada-en-polvo-mycryo-cacao-barry-550-g-2","status":"publish","type":"product","link":"https:\/\/glotomania.com\/pt-pt\/p\/manteca-de-cacao-desodorizada-en-polvo-mycryo-cacao-barry-550-g-2\/","title":{"rendered":"Manteiga De Cacau Desodorizada Em P\u00d3 \u201cmycryo\u201d Cacao Barry \u2013 550 G"},"content":{"rendered":"<div>&nbsp;<\/div>\n<div><span style=\"font-size:14px\"><span style=\"color:#000000\">Gra&ccedil;as ao seu <strong>sabor e aroma neutros<\/strong>, n&atilde;o interfere no perfil sensorial do chocolate, tornando-se uma base ideal para <strong>melhorar a fluidez, o brilho e a textura<\/strong>, bem como para t&eacute;cnicas decorativas avan&ccedil;adas. Apresenta cor clara, textura est&aacute;vel e excelente estabilidade t&eacute;rmica.<\/span><\/span><br \/>\n&nbsp;<\/div>\n<div><span style=\"font-size:14px\"><span style=\"color:#000000\">Um ingrediente indispens&aacute;vel em ateliers, pastelarias e cozinhas criativas.<\/span><\/span><br \/>\n&nbsp;<\/div>\n<div><span style=\"font-size:14px\"><span style=\"color:#000000\"><strong>Aplica&ccedil;&otilde;es:<\/strong><\/span><\/span><\/div>\n<ul>\n<li><span style=\"font-size:14px\"><span style=\"color:#000000\">Ajustar a fluidez do chocolate para moldagem fina e coberturas. Recomenda-se adicionar entre <strong>1% e 8% de manteiga de cacau<\/strong>, conforme a aplica&ccedil;&atilde;o (moldagem, banho, pulveriza&ccedil;&atilde;o ou decora&ccedil;&atilde;o).<\/span><\/span><\/li>\n<li><span style=\"font-size:14px\"><span style=\"color:#000000\">Melhorar o brilho e o desmolde em bombonaria.<\/span><\/span><\/li>\n<li><span style=\"font-size:14px\"><span style=\"color:#000000\">Misturar com corantes lipossol&uacute;veis para aerografia e sprays decorativos.<\/span><\/span><\/li>\n<li><span style=\"font-size:14px\"><span style=\"color:#000000\">Criar decora&ccedil;&otilde;es em chocolate, efeitos veludo e acabamentos art&iacute;sticos.<\/span><\/span><\/li>\n<li><span style=\"font-size:14px\"><span style=\"color:#000000\">Utiliza&ccedil;&atilde;o em ganaches, cremes t&eacute;cnicos e pastelaria avan&ccedil;ada.<\/span><\/span><\/li>\n<li><span style=\"font-size:14px\"><span style=\"color:#000000\">Permite resultados uniformes, est&aacute;veis e repet&iacute;veis, mesmo em trabalhos exigentes.<\/span><\/span><\/li>\n<\/ul>\n<div><span style=\"font-size:14px\"><span style=\"color:#000000\"><em>Produto elaborado com cacau proveniente do <strong>programa Cocoa Horizons<\/strong>, uma iniciativa do grupo Callebaut que apoia os agricultores, promove pr&aacute;ticas sustent&aacute;veis e melhora as condi&ccedil;&otilde;es de vida das comunidades produtoras de cacau.<\/em><\/span><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Manteiga de cacau em p\u00f3 de qualidade profissional e alta pureza (100% manteiga de cacau), desenvolvida para elevar o trabalho em chocolate e pastelaria a um n\u00edvel superior. O seu formato em p\u00f3 torna-a extremamente vers\u00e1til, precisa e f\u00e1cil de utilizar.<\/p>\n","protected":false},"featured_media":383200,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"pwb-brand":[],"product_brand":[],"product_cat":[2952,1880,2905,1829,3018,1844,2882],"product_tag":[],"class_list":{"0":"post-390868","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-coberturas-2","7":"product_cat-cobertura","8":"product_cat-data-de-expiracao-proxima","9":"product_cat-ingredientes","10":"product_cat-ingredientes-de-pastelaria-2","11":"product_cat-ingredientes-reposteria","12":"product_cat-mantecas-y-grasas","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"acf":[],"df_price":38.95,"df_sale_price":"","df_regular_price":38.95,"df_image_link":"https:\/\/glotomania.com\/wp-content\/uploads\/2026\/02\/img_28323_afb3a0453b3c55e779e3f454169047fc_1.jpg","brands":[],"_links":{"self":[{"href":"https:\/\/glotomania.com\/pt-pt\/wp-json\/wp\/v2\/product\/390868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/glotomania.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/glotomania.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/glotomania.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=390868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/glotomania.com\/pt-pt\/wp-json\/wp\/v2\/media\/383200"}],"wp:attachment":[{"href":"https:\/\/glotomania.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=390868"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/glotomania.com\/pt-pt\/wp-json\/wp\/v2\/pwb-brand?post=390868"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/glotomania.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=390868"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/glotomania.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=390868"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/glotomania.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=390868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}